{"id":99693,"date":"2026-07-15T13:01:39","date_gmt":"2026-07-15T13:01:39","guid":{"rendered":"https:\/\/elliberal.com.mx\/index.php\/2026\/07\/15\/reduccion-significativa-en-el-impacto-ambiental-del-cablebus-en-puebla-con-plan-de-trasplante-y-compensacion-ecologica\/"},"modified":"2026-07-15T19:01:42","modified_gmt":"2026-07-15T19:01:42","slug":"reduccion-significativa-en-el-impacto-ambiental-del-cablebus-en-puebla-con-plan-de-trasplante-y-compensacion-ecologica","status":"publish","type":"post","link":"https:\/\/elliberal.com.mx\/index.php\/2026\/07\/15\/reduccion-significativa-en-el-impacto-ambiental-del-cablebus-en-puebla-con-plan-de-trasplante-y-compensacion-ecologica\/","title":{"rendered":"Reducci\u00f3n significativa en el impacto ambiental del Cableb\u00fas en Puebla, con plan de trasplante y compensaci\u00f3n ecol\u00f3gica"},"content":{"rendered":"<p>El coordinador del Gabinete estatal, Jos\u00e9 Luis Garc\u00eda Parra, inform\u00f3 que gracias a m\u00e1s de 80 estudios t\u00e9cnicos realizados para el Sistema de Transporte por Cable, se logr\u00f3 reducir de 980 a 77 el n\u00famero de \u00e1rboles que sufrir\u00e1n alg\u00fan tipo de intervenci\u00f3n por la construcci\u00f3n del proyecto.  <\/p>\n<p>Durante su comparecencia ante el Congreso del Estado, Garc\u00eda Parra detall\u00f3 que de esos 77 \u00e1rboles, nueve corresponden a especies nativas, mientras que 68 son especies ex\u00f3ticas, las cuales afectan negativamente el desarrollo de la fauna y la vegetaci\u00f3n propias de la regi\u00f3n.  <\/p>\n<p>El funcionario destac\u00f3 que la mayor\u00eda de los \u00e1rboles ser\u00e1n trasplantados y que el programa de compensaci\u00f3n ambiental se enfocar\u00e1 exclusivamente en el uso de especies end\u00e9micas de Puebla. \u201cSer\u00e1 fundamental que solo se usen especies end\u00e9micas de Puebla en la mitigaci\u00f3n\u201d, subray\u00f3.  <\/p>\n<p>Adem\u00e1s, explic\u00f3 que el proyecto contar\u00e1 con un plan integral de manejo ambiental que incluye acciones para el control de emisiones, ruido, manejo de residuos s\u00f3lidos y medidas para la conservaci\u00f3n de la fauna y la biodiversidad durante las etapas de construcci\u00f3n y operaci\u00f3n.  <\/p>\n<p>Garc\u00eda Parra asegur\u00f3 que las zonas donde se desarrollar\u00e1n las obras no solo ser\u00e1n restauradas, sino que tambi\u00e9n recibir\u00e1n acciones de mejoramiento urbano y ambiental, con el objetivo de recuperar y dignificar los espacios p\u00fablicos intervenidos.  <\/p>\n<p>Estas precisiones forman parte de la informaci\u00f3n t\u00e9cnica presentada por el Gobierno del Estado para responder a las inquietudes sobre el impacto ambiental del Cableb\u00fas, uno de los temas centrales en el debate p\u00fablico sobre este sistema de transporte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El coordinador del Gabinete estatal, Jos\u00e9 Luis Garc\u00eda Parra, inform\u00f3 que gracias a m\u00e1s de 80 estudios t\u00e9cnicos realizados para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[16],"tags":[],"class_list":["post-99693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"_links":{"self":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=99693"}],"version-history":[{"count":1,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99693\/revisions"}],"predecessor-version":[{"id":99694,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99693\/revisions\/99694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/media\/99692"}],"wp:attachment":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=99693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=99693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=99693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}