{"id":99651,"date":"2026-07-15T10:48:18","date_gmt":"2026-07-15T10:48:18","guid":{"rendered":"https:\/\/elliberal.com.mx\/index.php\/2026\/07\/15\/argentina-impulsa-ley-para-eliminar-limites-a-la-compra-de-tierras-por-extranjeros\/"},"modified":"2026-07-15T16:48:21","modified_gmt":"2026-07-15T16:48:21","slug":"argentina-impulsa-ley-para-eliminar-limites-a-la-compra-de-tierras-por-extranjeros","status":"publish","type":"post","link":"https:\/\/elliberal.com.mx\/index.php\/2026\/07\/15\/argentina-impulsa-ley-para-eliminar-limites-a-la-compra-de-tierras-por-extranjeros\/","title":{"rendered":"Argentina impulsa ley para eliminar l\u00edmites a la compra de tierras por extranjeros"},"content":{"rendered":"<p>El Gobierno de Argentina presentar\u00e1 en el Senado un proyecto para modificar la Ley 26.737 de Tierras Rurales, con el prop\u00f3sito de eliminar las restricciones que actualmente limitan la adquisici\u00f3n de campos por parte de extranjeros.  <\/p>\n<p>La iniciativa, reportada por Clar\u00edn, forma parte de un paquete normativo relacionado con la inviolabilidad de la propiedad privada y busca abrir el mercado rural a inversores internacionales. En la actualidad, la legislaci\u00f3n vigente impide que los extranjeros posean m\u00e1s del 15% del total de tierras rurales a nivel nacional, provincial y municipal.  <\/p>\n<p>El vocero presidencial, Adri\u00e1n Ravier, defendi\u00f3 la propuesta al se\u00f1alar que la normativa vigente \u201ccriminaliz\u00f3 de facto la compra de tierras por parte de extranjeros\u201d, lo que, a su juicio, contradice el esp\u00edritu constitucional que reconoce derechos civiles tanto a nacionales como a extranjeros.  <\/p>\n<p>Ravier explic\u00f3 que estas restricciones han frenado inversiones significativas, especialmente en sectores foresto-industriales de regiones como el NEA, Cuyo y la Patagonia, donde existen \u201cproyectos millonarios que no pueden desarrollarse por estas trabas\u201d.  <\/p>\n<p>El proyecto distinguir\u00e1 entre inversores privados y Estados extranjeros. En este sentido, el funcionario precis\u00f3 que gobiernos, empresas estatales o sociedades controladas por ellos deber\u00e1n cumplir con mayores exigencias. Actualmente, estos actores pueden comprar hasta 1,000 hect\u00e1reas sin restricciones, pero con la nueva ley requerir\u00e1n autorizaci\u00f3n espec\u00edfica.  <\/p>\n<p>Desde el sector inmobiliario rural, el debate tambi\u00e9n se centra en el impacto econ\u00f3mico. Lucas Palma, presidente de la C\u00e1mara Inmobiliaria Rural, afirm\u00f3 que lo que realmente podr\u00eda elevar el valor de los campos son medidas m\u00e1s amplias, como la eliminaci\u00f3n de retenciones y reglas claras para la inversi\u00f3n.  <\/p>\n<p>Por su parte, Federico Nordheimer, titular de Nordheimer Campos y Estancias, consider\u00f3 que el temor a una compra masiva de tierras por extranjeros responde m\u00e1s a un imaginario hist\u00f3rico que a la realidad del mercado. \u201cEs un miedo comprensible, con ra\u00edces hist\u00f3ricas y culturales profundas, pero quienes trabajamos d\u00eda a d\u00eda en el mercado inmobiliario rural sabemos que la realidad del sector cuenta una historia bastante diferente\u201d, se\u00f1al\u00f3.  <\/p>\n<p>Actualmente, Argentina cuenta con cerca de 266.7 millones de hect\u00e1reas rurales, de las cuales 16.2 millones est\u00e1n en manos extranjeras, lo que representa el 6% del total. Este proyecto podr\u00eda abrir un nuevo cap\u00edtulo en la discusi\u00f3n sobre inversi\u00f3n, soberan\u00eda, producci\u00f3n agr\u00edcola y control territorial.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/catrina_nortena\/status\/2077146920322060355\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Argentina presentar\u00e1 en el Senado un proyecto para modificar la Ley 26.737 de Tierras Rurales, con el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[17],"tags":[],"class_list":["post-99651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=99651"}],"version-history":[{"count":1,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99651\/revisions"}],"predecessor-version":[{"id":99652,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99651\/revisions\/99652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/media\/99650"}],"wp:attachment":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=99651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=99651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=99651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}