{"id":99570,"date":"2026-07-14T14:45:19","date_gmt":"2026-07-14T14:45:19","guid":{"rendered":"https:\/\/elliberal.com.mx\/index.php\/2026\/07\/14\/pasajero-queda-parcialmente-succionado-tras-desprendimiento-de-ventana-en-vuelo-de-ryanair\/"},"modified":"2026-07-14T20:45:22","modified_gmt":"2026-07-14T20:45:22","slug":"pasajero-queda-parcialmente-succionado-tras-desprendimiento-de-ventana-en-vuelo-de-ryanair","status":"publish","type":"post","link":"https:\/\/elliberal.com.mx\/index.php\/2026\/07\/14\/pasajero-queda-parcialmente-succionado-tras-desprendimiento-de-ventana-en-vuelo-de-ryanair\/","title":{"rendered":"Pasajero queda parcialmente succionado tras desprendimiento de ventana en vuelo de Ryanair"},"content":{"rendered":"<p>Un incidente de gravedad ocurri\u00f3 el viernes 10 de julio a bordo de un vuelo de Ryanair que cubr\u00eda la ruta entre Tesal\u00f3nica, Grecia, y Memmingen, Alemania. Poco despu\u00e9s del despegue, una ventana de la aeronave se desprendi\u00f3, provocando la despresurizaci\u00f3n de la cabina y dejando a un pasajero parcialmente succionado hacia el exterior del avi\u00f3n.  <\/p>\n<p>Seg\u00fan los testimonios de los pasajeros, tras el fuerte estruendo se activaron las mascarillas de ox\u00edgeno debido a la p\u00e9rdida de presi\u00f3n. El hombre afectado, un ciudadano serbio de 61 a\u00f1os que viajaba junto a la ventana, fue impulsado hacia el exterior hasta la altura de los hombros. Su esposa y otros pasajeros lograron sujetarlo durante varios minutos mientras la tripulaci\u00f3n iniciaba un descenso de emergencia para regresar al aeropuerto.  <\/p>\n<p>Ryanair inform\u00f3 que el vuelo FR1879 aterriz\u00f3 sin contratiempos y que los pasajeros fueron trasladados a la terminal. El hombre lesionado recibi\u00f3 atenci\u00f3n m\u00e9dica inmediata y fue hospitalizado. Las autoridades sanitarias indicaron que sufri\u00f3 quemaduras por fricci\u00f3n y lesiones compatibles con la exposici\u00f3n al intenso flujo de aire, aunque permanece estable y consciente.  <\/p>\n<p>Por su parte, las autoridades han abierto una investigaci\u00f3n para determinar las causas que provocaron el desprendimiento de la ventana. Este tipo de incidentes subraya la importancia de los protocolos de seguridad y la atenci\u00f3n inmediata de la tripulaci\u00f3n para salvaguardar la vida de los pasajeros.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/aviationbrk\/status\/2075494035792285793?s=20\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un incidente de gravedad ocurri\u00f3 el viernes 10 de julio a bordo de un vuelo de Ryanair que cubr\u00eda la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99569,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[17],"tags":[],"class_list":["post-99570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=99570"}],"version-history":[{"count":1,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99570\/revisions"}],"predecessor-version":[{"id":99571,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99570\/revisions\/99571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/media\/99569"}],"wp:attachment":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=99570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=99570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=99570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}