{"id":99465,"date":"2026-07-13T15:52:37","date_gmt":"2026-07-13T15:52:37","guid":{"rendered":"https:\/\/elliberal.com.mx\/index.php\/2026\/07\/13\/nayib-bukele-obtiene-candidatura-unanime-para-buscar-un-tercer-mandato-en-el-salvador\/"},"modified":"2026-07-13T21:52:39","modified_gmt":"2026-07-13T21:52:39","slug":"nayib-bukele-obtiene-candidatura-unanime-para-buscar-un-tercer-mandato-en-el-salvador","status":"publish","type":"post","link":"https:\/\/elliberal.com.mx\/index.php\/2026\/07\/13\/nayib-bukele-obtiene-candidatura-unanime-para-buscar-un-tercer-mandato-en-el-salvador\/","title":{"rendered":"Nayib Bukele obtiene candidatura un\u00e1nime para buscar un tercer mandato en El Salvador"},"content":{"rendered":"<p>El presidente de El Salvador, Nayib Bukele, fue ratificado de manera un\u00e1nime como candidato presidencial de su partido, Nuevas Ideas, para las elecciones generales que se celebrar\u00e1n en febrero de 2027. As\u00ed lo inform\u00f3 el domingo el conglomerado pol\u00edtico, confirmando que Bukele y el vicepresidente F\u00e9lix Ulloa repetir\u00e1n f\u00f3rmula presidencial por tercera ocasi\u00f3n consecutiva, tras no enfrentar oposici\u00f3n interna.  <\/p>\n<p>Bukele, quien lleg\u00f3 al poder en 2019 y actualmente cumple un segundo mandato, ha impulsado reformas legales controvertidas que le han permitido buscar la reelecci\u00f3n. En diciembre pasado, el mandatario expres\u00f3 su disposici\u00f3n a permanecer en la presidencia durante una d\u00e9cada m\u00e1s.  <\/p>\n<p>En julio de 2025, el Congreso salvadore\u00f1o, dominado por una amplia mayor\u00eda oficialista, aprob\u00f3 una enmienda constitucional que redujo a tres a\u00f1os el periodo presidencial iniciado en 2024. Esta modificaci\u00f3n abri\u00f3 la posibilidad de que Bukele gobierne en un pr\u00f3ximo mandato de seis a\u00f1os en lugar de cinco, lo que, de ser reelegido en 2027, extender\u00eda su gesti\u00f3n hasta el 31 de mayo de 2033.  <\/p>\n<p>Adem\u00e1s, el Legislativo elimin\u00f3 los l\u00edmites constitucionales que imped\u00edan la reelecci\u00f3n presidencial indefinida, facilitando as\u00ed que Bukele pueda mantenerse en el poder m\u00e1s all\u00e1 de los periodos tradicionales.  <\/p>\n<p>El presidente mantiene altos niveles de popularidad y preferencia electoral, en gran medida por la pol\u00edtica de r\u00e9gimen de excepci\u00f3n vigente desde 2022, que ha logrado reducir los homicidios en m\u00e1s de un 90%, seg\u00fan cifras oficiales.  <\/p>\n<p>Para las elecciones de febrero pr\u00f3ximo, se prev\u00e9 que Bukele enfrente \u00fanicamente al candidato del partido izquierdista Frente Farabundo Mart\u00ed para la Liberaci\u00f3n Nacional (FMLN), cuya candidatura ser\u00e1 definida a finales de julio. Cabe recordar que Bukele fue expulsado del FMLN en 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de El Salvador, Nayib Bukele, fue ratificado de manera un\u00e1nime como candidato presidencial de su partido, Nuevas Ideas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99464,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[17],"tags":[],"class_list":["post-99465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=99465"}],"version-history":[{"count":1,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99465\/revisions"}],"predecessor-version":[{"id":99466,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/99465\/revisions\/99466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/media\/99464"}],"wp:attachment":[{"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=99465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=99465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elliberal.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=99465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}